{"id":999,"count":17,"description":"","link":"https:\/\/labsalliebe.com\/en\/tag\/food-guide\/","name":"Food Guide","slug":"food-guide","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Food Guide Archive - Labsalliebe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/labsalliebe.com\/en\/tag\/food-guide\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Food Guide Archive - Labsalliebe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/labsalliebe.com\/en\/tag\/food-guide\/\" \/>\n<meta property=\"og:site_name\" content=\"Labsalliebe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/labsalliebe.com\\\/en\\\/tag\\\/food-guide\\\/\",\"url\":\"https:\\\/\\\/labsalliebe.com\\\/en\\\/tag\\\/food-guide\\\/\",\"name\":\"Food Guide Archive - Labsalliebe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/labsalliebe.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/labsalliebe.com\\\/en\\\/tag\\\/food-guide\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/labsalliebe.com\\\/en\\\/tag\\\/food-guide\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/labsalliebe.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Food Guide\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/labsalliebe.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/labsalliebe.com\\\/en\\\/\",\"name\":\"Labsalliebe\",\"description\":\"Food &amp; Lifestyleblog\",\"publisher\":{\"@id\":\"https:\\\/\\\/labsalliebe.com\\\/en\\\/#\\\/schema\\\/person\\\/2a151a4e86059b6a51f302b6a33a2f06\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/labsalliebe.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/labsalliebe.com\\\/en\\\/#\\\/schema\\\/person\\\/2a151a4e86059b6a51f302b6a33a2f06\",\"name\":\"susann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/labsalliebe.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/09\\\/cropped-labsalliebe-logo2020.jpg\",\"url\":\"https:\\\/\\\/labsalliebe.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/09\\\/cropped-labsalliebe-logo2020.jpg\",\"contentUrl\":\"https:\\\/\\\/labsalliebe.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/09\\\/cropped-labsalliebe-logo2020.jpg\",\"width\":190,\"height\":142,\"caption\":\"susann\"},\"logo\":{\"@id\":\"https:\\\/\\\/labsalliebe.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/09\\\/cropped-labsalliebe-logo2020.jpg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Food Guide Archive - Labsalliebe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/labsalliebe.com\/en\/tag\/food-guide\/","og_locale":"en_US","og_type":"article","og_title":"Food Guide Archive - Labsalliebe","og_url":"https:\/\/labsalliebe.com\/en\/tag\/food-guide\/","og_site_name":"Labsalliebe","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/labsalliebe.com\/en\/tag\/food-guide\/","url":"https:\/\/labsalliebe.com\/en\/tag\/food-guide\/","name":"Food Guide Archive - Labsalliebe","isPartOf":{"@id":"https:\/\/labsalliebe.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/labsalliebe.com\/en\/tag\/food-guide\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/labsalliebe.com\/en\/tag\/food-guide\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/labsalliebe.com\/en\/"},{"@type":"ListItem","position":2,"name":"Food Guide"}]},{"@type":"WebSite","@id":"https:\/\/labsalliebe.com\/en\/#website","url":"https:\/\/labsalliebe.com\/en\/","name":"Labsalliebe","description":"Food &amp; Lifestyleblog","publisher":{"@id":"https:\/\/labsalliebe.com\/en\/#\/schema\/person\/2a151a4e86059b6a51f302b6a33a2f06"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/labsalliebe.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/labsalliebe.com\/en\/#\/schema\/person\/2a151a4e86059b6a51f302b6a33a2f06","name":"susann","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/labsalliebe.com\/en\/wp-content\/uploads\/sites\/2\/2022\/09\/cropped-labsalliebe-logo2020.jpg","url":"https:\/\/labsalliebe.com\/en\/wp-content\/uploads\/sites\/2\/2022\/09\/cropped-labsalliebe-logo2020.jpg","contentUrl":"https:\/\/labsalliebe.com\/en\/wp-content\/uploads\/sites\/2\/2022\/09\/cropped-labsalliebe-logo2020.jpg","width":190,"height":142,"caption":"susann"},"logo":{"@id":"https:\/\/labsalliebe.com\/en\/wp-content\/uploads\/sites\/2\/2022\/09\/cropped-labsalliebe-logo2020.jpg"}}]}},"_links":{"self":[{"href":"https:\/\/labsalliebe.com\/en\/wp-json\/wp\/v2\/tags\/999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labsalliebe.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/labsalliebe.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/labsalliebe.com\/en\/wp-json\/wp\/v2\/posts?tags=999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}